{"id":220,"date":"2013-12-14T20:52:32","date_gmt":"2013-12-14T18:52:32","guid":{"rendered":"http:\/\/www.kunstkurs-online.de\/kunst-blog-msa\/?p=220"},"modified":"2018-12-22T01:57:52","modified_gmt":"2018-12-21T23:57:52","slug":"kuenstlerportrait-franz-marc","status":"publish","type":"post","link":"http:\/\/www.kunstkurs-online.de\/kunst-blog-msa\/kunst-kunstler\/kuenstlerportrait-franz-marc\/","title":{"rendered":"K\u00fcnstlerportrait &#8211; Franz Marc"},"content":{"rendered":"<p><a href=\"http:\/\/www.amazon.de\/gp\/product\/394361607X\/ref=as_li_tf_tl?ie=UTF8&amp;camp=1638&amp;creative=6742&amp;creativeASIN=394361607X&amp;linkCode=as2&amp;tag=malenzeichnai-21\" target=\"_blank\" rel=\"noopener\">Franz Marc<\/a>*\u00a0z\u00e4hlt bis heute zu den bedeutendsten Malern des <a href=\"http:\/\/www.amazon.de\/gp\/product\/3652000544\/ref=as_li_tf_tl?ie=UTF8&amp;camp=1638&amp;creative=6742&amp;creativeASIN=3652000544&amp;linkCode=as2&amp;tag=malenzeichnai-21\" target=\"_blank\" rel=\"noopener\">Expressionismus<\/a>*. Er malte bis zu seinem fr\u00fchen Tod viele Tiere, zu denen er eine besondere Beziehung hatte. Marc malte neben Katzen, F\u00fcchsen und K\u00fchen auch immer wieder Pferde.<\/p>\n<h2>Franz Marc<\/h2>\n<p>Geboren wurde <a title=\"Franz Marc\" href=\"http:\/\/de.wikipedia.org\/wiki\/Franz_Marc\" target=\"_blank\" rel=\"noopener\">Franz Marc<\/a> 1880 als Sohn eines Kunstmalers in M\u00fcnchen. Nach dem Besuch des Gymnasiums wollte er urspr\u00fcnglich Theologe werden, aber er entschied sich dann doch f\u00fcr ein Studium an der M\u00fcnchner Kunstakademie. Ausschlaggebend war ein Besuch von Franz Marc in Paris, wo er die Bilder des ber\u00fchmten Vincent van Gogh zum ersten Mal sah. Von noch gr\u00f6\u00dferer Bedeutung f\u00fcr den jungen Maler Franz Marc war aber die Begegnung mit August Macke und <a href=\"http:\/\/www.amazon.de\/gp\/product\/3822863602\/ref=as_li_tf_tl?ie=UTF8&amp;camp=1638&amp;creative=6742&amp;creativeASIN=3822863602&amp;linkCode=as2&amp;tag=malenzeichnai-21\" target=\"_blank\" rel=\"noopener\">Wassili Kandinsky<\/a>*. Mit Macke und Kandinsky gr\u00fcndete Marc im Jahre 1912 die K\u00fcnstlervereinigung \u201eDer blaue Reiter&#8220;. Kurz nachdem Franz Marc sich mit einem eigenen Atelier im bayerischen Kochel am See selbstst\u00e4ndig gemacht hatte, erhielten er und August Macke 1914 ihre Stellungsbefehle. Franz Marc fiel am 4. M\u00e4rz 1916 in der N\u00e4he von Verdun.<\/p>\n<h5 style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter\" src=\"\/kunst-blog-artikel\/bilder-blog\/franz-marc-04.jpg\" alt=\"Expressionismus - Gem\u00e4lde\" \/>K\u00e4mpfende Formen, von Franz Marc, 1914 (Replikat)<\/h5>\n<h5 style=\"text-align: center;\"><img decoding=\"async\" src=\"\/kunst-blog-artikel\/bilder-blog\/franz-marc-12.jpg\" alt=\"Expressionismus - Malerei und Kunst\" \/><br \/>\n Tirol, von Franz Marc, 1914 (Replikat)<\/h5>\n<h3>Die gro\u00dfen blauen Pferde<\/h3>\n<p>Franz Marc mochte ganz besonders Pferde. Es ist daher nicht weiter verwunderlich, dass er sie immer wieder malte. 1911 begann er mit dem Gem\u00e4lde \u201eDie gro\u00dfen blauen Pferde&#8220;. Auf diesem Bild wird Marcs Leidenschaft f\u00fcr Pferde sehr deutlich. F\u00fcr ihn waren Pferde die urspr\u00fcnglichsten und auch die vollkommensten Gesch\u00f6pfe, kraftvoll und elegant zugleich. Das Gem\u00e4lde zeigt drei blaue Pferde vor einer Landschaft, die ganz in Rott\u00f6nen gehalten ist. Farben spielten f\u00fcr Franz Marc eine ganz besonders Rolle. Sie hatten alle eine bestimmte Symbolik. Nicht umsonst w\u00e4hlte er f\u00fcr \u201eDie gro\u00dfen blauen Pferde&#8220; die Farbe Blau, denn diese stand f\u00fcr das Kraftvolle und M\u00e4nnliche. Gelb war alles Weibliche und Rot stand nur f\u00fcr die Materie.<\/p>\n<h3>USA<\/h3>\n<p>Um sich das Gem\u00e4lde \u201eDie gro\u00dfen blauen Pferde&#8220; von\u00a0<a href=\"http:\/\/www.amazon.de\/gp\/product\/394361607X\/ref=as_li_tf_tl?ie=UTF8&amp;camp=1638&amp;creative=6742&amp;creativeASIN=394361607X&amp;linkCode=as2&amp;tag=malenzeichnai-21\" target=\"_blank\" rel=\"noopener\">Franz Marc<\/a>* anzusehen, muss man in die USA reisen. Das Bild h\u00e4ngt im Walker Art Center in Minneapolis\/Minnesota.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Franz Marc*\u00a0z\u00e4hlt bis heute zu den bedeutendsten Malern des Expressionismus*. Er malte bis zu seinem fr\u00fchen Tod viele Tiere, zu denen er eine besondere Beziehung hatte. Marc malte neben Katzen, F\u00fcchsen und K\u00fchen auch immer wieder Pferde. Franz Marc Geboren wurde Franz Marc 1880 als Sohn eines Kunstmalers in M\u00fcnchen. Nach dem Besuch des Gymnasiums [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54],"tags":[],"_links":{"self":[{"href":"http:\/\/www.kunstkurs-online.de\/kunst-blog-msa\/wp-json\/wp\/v2\/posts\/220"}],"collection":[{"href":"http:\/\/www.kunstkurs-online.de\/kunst-blog-msa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.kunstkurs-online.de\/kunst-blog-msa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.kunstkurs-online.de\/kunst-blog-msa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.kunstkurs-online.de\/kunst-blog-msa\/wp-json\/wp\/v2\/comments?post=220"}],"version-history":[{"count":4,"href":"http:\/\/www.kunstkurs-online.de\/kunst-blog-msa\/wp-json\/wp\/v2\/posts\/220\/revisions"}],"predecessor-version":[{"id":373,"href":"http:\/\/www.kunstkurs-online.de\/kunst-blog-msa\/wp-json\/wp\/v2\/posts\/220\/revisions\/373"}],"wp:attachment":[{"href":"http:\/\/www.kunstkurs-online.de\/kunst-blog-msa\/wp-json\/wp\/v2\/media?parent=220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.kunstkurs-online.de\/kunst-blog-msa\/wp-json\/wp\/v2\/categories?post=220"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.kunstkurs-online.de\/kunst-blog-msa\/wp-json\/wp\/v2\/tags?post=220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}